{"id":9673,"date":"2020-11-11T09:47:30","date_gmt":"2020-11-11T12:47:30","guid":{"rendered":"http:\/\/revistabife.com\/?p=9673"},"modified":"2020-11-11T09:47:31","modified_gmt":"2020-11-11T12:47:31","slug":"crearon-un-registro-unico-de-denuncias-por-violencia-de-genero","status":"publish","type":"post","link":"https:\/\/revistabife.com\/index.php\/2020\/11\/11\/crearon-un-registro-unico-de-denuncias-por-violencia-de-genero\/","title":{"rendered":"Crearon un registro \u00fanico de denuncias por violencia de g\u00e9nero"},"content":{"rendered":"\n<p class=\"has-drop-cap has-medium-font-size\">El Ministerio de Salud de la Naci\u00f3n aprob\u00f3 la creaci\u00f3n del Sistema \u00danico de Registro de Denuncias por Violencia de G\u00e9nero (URGE).<\/p>\n\n\n\n<p class=\"has-medium-font-size\">URGE tiene como objetivo reunir en un solo sistema toda la informaci\u00f3n relevante de las denuncias recepcionadas en las dependencias policiales en materia de violencia de g\u00e9nero. Adem\u00e1s, establece un protocolo de actuaci\u00f3n policial ante denuncias sobre la materia.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">La Resoluci\u00f3n 408\/2020, firmada por la ministra Sabina Frederic, ser\u00e1 implementada por la Polic\u00eda Federal, la Polic\u00eda Aeroportuaria, Prefectura y Gendarmer\u00eda. El documento invita a los gobiernos provinciales y de la Ciudad de Buenos Aires a adherir al sistema.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Los ministerios de Mujeres, G\u00e9neros y Diversidad y de Justicia y Derechos Humanos conformar\u00e1n una mesa interministerial para una puesta al di\u00e1logo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Salud de la Naci\u00f3n aprob\u00f3 la creaci\u00f3n del Sistema \u00danico de Registro<\/p>\n","protected":false},"author":1,"featured_media":9674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[32],"tags":[378],"class_list":["post-9673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-genero"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/9673"}],"collection":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/comments?post=9673"}],"version-history":[{"count":1,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/9673\/revisions"}],"predecessor-version":[{"id":9675,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/9673\/revisions\/9675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/media\/9674"}],"wp:attachment":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/media?parent=9673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/categories?post=9673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/tags?post=9673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}