{"id":7869,"date":"2020-09-14T16:21:42","date_gmt":"2020-09-14T19:21:42","guid":{"rendered":"http:\/\/revistabife.com\/?p=7869"},"modified":"2020-09-14T16:21:44","modified_gmt":"2020-09-14T19:21:44","slug":"intenso-trabajo-de-salud-en-intendente-alvear","status":"publish","type":"post","link":"https:\/\/revistabife.com\/index.php\/2020\/09\/14\/intenso-trabajo-de-salud-en-intendente-alvear\/","title":{"rendered":"Intenso trabajo de Salud en Intendente Alvear"},"content":{"rendered":"\n<p class=\"has-drop-cap has-medium-font-size\">Personal del Ministerio de Salud desarrolla, desde hace varios d\u00edas, una intensa labor preventiva, de contenci\u00f3n y detecci\u00f3n de casos en Intendente Alvear y zona afectada por este brote. La buena noticia llega en una baja en el n\u00famero de casos notificados en las \u00faltimas horas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">El director del CODES, <strong>Juan Barbero,<\/strong> el director de APS, <strong>Ariel Paladini<\/strong> y el director del Hospital de Intendente Alvear, <strong>Gustavo Mart\u00ednez<\/strong>, encabezan hoy las tareas que contin\u00faan sin descanso en la norte\u00f1a localidad.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><br>\u201cDesde el primer brote de COVID-19 en Catril\u00f3 no hab\u00edamos tenido otro de la magnitud,<strong> incluso ahora llegando a superarlo, de lo que fue en estos d\u00edas Intendente Alvear<\/strong>. El trabajo de los equipos t\u00e9cnicos de Salud es para reforzar al equipo local que, por la magnitud del brote, muchas veces requiere la presencia de la Coordinaci\u00f3n de Emergencia, de la Direcci\u00f3n de Atenci\u00f3n Primaria, de la Direcci\u00f3n de Epidemiolog\u00eda, de la Zona Sanitaria, para definir una estrategia que empieza siendo local y que luego, inmediatamente,<strong> pasa a ser regional porque no es \u00fanicamente la localidad de Intendente Alvear afectada sino que tambi\u00e9n lo est\u00e1 Bernardo Larroud\u00e9<\/strong>, que pr\u00e1cticamente estuvo desde el inicio del brote, las dos vuelven a fase 1 para tratar de frenar la curva en ascenso de transmisibilidad y lo que fue replicando en las localidades vecinas, Hilario Lagos, Sarah, Realic\u00f3, Rancul\u201d, expres\u00f3 Juan Barbero.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><br>Hoy la presencia de parte del equipo est\u00e1 en Intendente Alvear, \u201cdonde hay una curva decreciente de la notificaci\u00f3n de casos, eso es algo que nos alienta a pensar que se viene trabajando con una estrategia de abordaje adecuada y con la mira en lo que est\u00e1 pasando en la regi\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><br>El eje de la labor se da en el Plan Detectar, tratando de dar con las personas que tienen pocos s\u00edntomas, o ninguno, a fin de aislarlo, \u201cnos da una tranquilidad el hecho de que la fase 1 disminuye considerablemente el flujo de contacto entre las personas. Y, si reforzamos el detectar y la posibilidad de encontrarnos con algunas personas positivas, con pocos s\u00edntomas, que ah\u00ed est\u00e1 la estrategia de abordaje del equipo, en ir a buscar el contacto estrecho, en interrogar la presencia de s\u00edntomas respiratorios, en buscar nuestra poblaci\u00f3n vulnerable, nuestros adultos mayores, personas con comorbilidades, de tratar de detectar esos pacientes para intentar hacer un bloqueo de la misma manera que se lo hizo en Catril\u00f3\u201d.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><br>Barbero destac\u00f3 la decisi\u00f3n del Gobierno provincial de descomprimir la tensi\u00f3n que genera tener m\u00e1s de 100 personas positivas en una localidad peque\u00f1a, lo que muchas veces dificulta la tarea de abordaje. \u201cPor eso es que el Ministerio de Salud y el Gobierno de La Pampa dispone los lugares de internaci\u00f3n en los centros hoteleros, donde se le puede hacer un seguimiento m\u00e1s adecuado.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"> Se est\u00e1n contemplando las diferentes alternativas, muchas de las personas en estos momentos que fueron positivas y que han tenido contactos estrechos, est\u00e1n finalizando su etapa de asilamiento. Eso es una buena noticia y muchos van a ir recibiendo las altas en estos d\u00edas.<strong> Estamos esperando esa progresi\u00f3n de los n\u00fameros, muy atentos a detectar, a aislar, a registrar, identificar y a que se pueda controlar en el menor tiempo posible el impacto del brote<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><br>A modo de cierre, el responsable del CODES remarc\u00f3 la importancia de la labor de investigaci\u00f3n, seguimiento, trazabilidad de los casos, \u201clo que lleva mucho tiempo y requiere un gran esfuerzo de todo el equipo\u201d.<br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal del Ministerio de Salud desarrolla, desde hace varios d\u00edas, una intensa labor preventiva, de<\/p>\n","protected":false},"author":1,"featured_media":7754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[32],"tags":[670,1652],"class_list":["post-7869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-covid-19","tag-intendente-alvear"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/7869"}],"collection":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/comments?post=7869"}],"version-history":[{"count":1,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/7869\/revisions"}],"predecessor-version":[{"id":7870,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/7869\/revisions\/7870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/media\/7754"}],"wp:attachment":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/media?parent=7869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/categories?post=7869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/tags?post=7869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}