{"id":7867,"date":"2020-09-14T15:14:55","date_gmt":"2020-09-14T18:14:55","guid":{"rendered":"http:\/\/revistabife.com\/?p=7867"},"modified":"2020-09-14T15:14:56","modified_gmt":"2020-09-14T18:14:56","slug":"covid-19-en-la-pampa-4-nuevos-positivos-que-estaban-aislados-por-contactos-estrechos-y-4-161-personas-aisladas","status":"publish","type":"post","link":"https:\/\/revistabife.com\/index.php\/2020\/09\/14\/covid-19-en-la-pampa-4-nuevos-positivos-que-estaban-aislados-por-contactos-estrechos-y-4-161-personas-aisladas\/","title":{"rendered":"Covid-19 en La Pampa: 4 nuevos positivos que estaban aislados por contactos estrechos y 4.161 personas aisladas"},"content":{"rendered":"\n<p class=\"has-drop-cap has-medium-font-size\">En horas de la ma\u00f1ana se finaliz\u00f3 con el procesamiento de 41 muestras en los laboratorios de Epidemiolog\u00eda, del Hospital Lucio Molas y del Gobernador Centeno, de las cuales 4 resultaron positivas para COVID-19. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Tres de las muestras confirmadas se corresponden a personas con residencia en la localidad de Intendente Alvear y 1 en General Acha. Los casos confirmados en el d\u00eda de la fecha eran contactos estrechos de casos positivos y se encontraban aislados como medida preventiva, evitando la diseminaci\u00f3n del virus.<br><strong>\u00a0<br>Situaci\u00f3n provincial<\/strong><br>En la Provincia, desde el inicio de la pandemia, se registraron un total de 414 casos positivos para COVID-19, de los cuales 212 permanecen activos, 3 han fallecido y 199 se han recuperado, entre ellos se encuentran 3 personas de la localidad de La Adela, a las que se le otorg\u00f3 el alta m\u00e9dica en el d\u00eda de hoy.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><br>Los casos confirmados activos est\u00e1n distribuidos de la siguiente manera: 122 en Intendente Alvear, 21 en Santa Rosa, 15 en 25 de Mayo, 24 en Bernardo Larroud\u00e9, 9 en General Pico, 3 en Catril\u00f3, 1 en Macach\u00edn, 4 en Toay, 3 en General Acha, 7 en Realic\u00f3, 2 en Rancul y 1 en Doblas.<br>Al d\u00eda de la fecha se encuentran aisladas un total de 4161 personas en toda la Provincia.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><br>Se encuentran internadas 12 personas confirmadas para COVID-19. En General Pico 7, 3 en terapia intensiva con pron\u00f3stico reservado y 4 en cl\u00ednica m\u00e9dica. En el Centro Emergente de Asistencia Respiratoria (CEAR) de Santa Rosa, se encuentran internadas 5 personas en cl\u00ednica m\u00e9dica.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la ma\u00f1ana se finaliz\u00f3 con el procesamiento de 41 muestras en los<\/p>\n","protected":false},"author":1,"featured_media":6208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[32],"tags":[670,44],"class_list":["post-7867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-covid-19","tag-la-pampa"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/7867"}],"collection":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/comments?post=7867"}],"version-history":[{"count":1,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/7867\/revisions"}],"predecessor-version":[{"id":7868,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/posts\/7867\/revisions\/7868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/media\/6208"}],"wp:attachment":[{"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/media?parent=7867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/categories?post=7867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistabife.com\/index.php\/wp-json\/wp\/v2\/tags?post=7867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}